{"id":30929,"date":"2026-05-12T15:52:02","date_gmt":"2026-05-12T13:52:02","guid":{"rendered":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/?p=30929"},"modified":"2026-05-12T16:01:20","modified_gmt":"2026-05-12T14:01:20","slug":"watchguard-stellt-rai-und-cloud-detection-and-response-vor","status":"publish","type":"post","link":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/2026\/05\/watchguard-stellt-rai-und-cloud-detection-and-response-vor\/","title":{"rendered":"WatchGuard stellt Rai&#x2122; und Cloud Detection and Response vor"},"content":{"rendered":"<p>Auf der diesj\u00e4hrigen Impact Partner Conference in Dubrovnik hat WatchGuard Technologies gleich zwei bedeutende Neuerungen vorgestellt: Rai&#x2122;, eine KI-gest\u00fctzte digitale Workforce, sowie WatchGuard Cloud Detection and Response (CloudDR).<\/p>\n<p>Beide L\u00f6sungen adressieren eine zentrale Herausforderung moderner Cybersicherheit: Angriffe werden zunehmend automatisiert, intelligent und rund um die Uhr ausgef\u00fchrt. Klassische Security-Teams sto\u00dfen dabei schnell an ihre Grenzen. Gleichzeitig reduzieren die neuen Technologien operative Aufw\u00e4nde, verk\u00fcrzen Reaktionszeiten und erm\u00f6glichen standardisierte sowie skalierbare Security-Services.<\/p>\n<p>Sowohl Rai&#x2122; (aktuell als Beta-Version) als auch WatchGuard CloudDR sind ab sofort verf\u00fcgbar.<\/p>\n<h4><!--more-->Rai&#x2122;: KI-Unterst\u00fctzung f\u00fcr moderne Sicherheitsumgebungen<\/h4>\n<p>Mit Rai&#x2122; (ausgesprochen \u201eRay\u201c) pr\u00e4sentiert WatchGuard eine agentische KI-L\u00f6sung, die als digitale Erweiterung bestehender Security-Teams fungiert. Die Plattform wurde entwickelt, um Sicherheitsereignisse kontinuierlich zu \u00fcberwachen, Bedrohungen fr\u00fchzeitig zu erkennen und automatisch darauf zu reagieren. W\u00e4hrend moderne Angreifer bereits autonome Systeme einsetzen, die kontinuierlich lernen und sich anpassen, arbeitet Rai&#x2122; als dauerhafter virtueller Mitarbeiter innerhalb der Unified Security Platform \u2013 rund um die Uhr 24\/7\/365.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30931 alignnone\" src=\"https:\/\/www.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard.png\" alt=\"\" width=\"2540\" height=\"1294\" srcset=\"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard.png 2540w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-300x153.png 300w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-1024x522.png 1024w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-768x391.png 768w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-1536x783.png 1536w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-2048x1043.png 2048w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-800x408.png 800w, https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-content\/uploads\/2026\/05\/watchguard-rai-dashboard-1200x611.png 1200w\" sizes=\"(max-width: 2540px) 100vw, 2540px\" \/><\/p>\n<h5>Die wichtigsten Funktionen von Rai&#x2122;:<\/h5>\n<ul>\n<li>Kontinuierliches Monitoring von IT-Umgebungen<\/li>\n<li>Automatische Erkennung und Korrelation von Bedrohungen<\/li>\n<li>Echtzeit-Reaktionen auf Sicherheitsvorf\u00e4lle<\/li>\n<li>Vollst\u00e4ndige Transparenz \u00fcber s\u00e4mtliche Aktionen und Entscheidungen<\/li>\n<li>Entlastung von IT-Teams bei zeitintensiven Routineaufgaben<\/li>\n<\/ul>\n<p>Durch den Einsatz von KI lassen sich Sicherheitsvorf\u00e4lle schneller erkennen und bearbeiten, w\u00e4hrend gleichzeitig interne Ressourcen entlastet werden. So gewinnen IT- und Security-Teams mehr Freiraum f\u00fcr strategische Aufgaben, komplexe Analysen und die Weiterentwicklung der eigenen Sicherheitsstrategie.<\/p>\n<h4>WatchGuard CloudDR erweitert den Schutz in Cloud- und SaaS-Umgebungen<\/h4>\n<p>Neben Rai&#x2122; wurde auch die Verf\u00fcgbarkeit von WatchGuard Cloud Detection and Response (CloudDR) angek\u00fcndigt. Die L\u00f6sung basiert auf der \u00dcbernahme von Perimeters.io und erweitert die Unified Security Platform um Schutzmechanismen f\u00fcr Cloud- und SaaS-Umgebungen.<\/p>\n<p>Gerade dort agieren moderne Angreifer zunehmend: in Identit\u00e4tssystemen, Cloud-Anwendungen und unkontrollierten SaaS-Diensten.<\/p>\n<h5>CloudDR bietet unter anderem:<\/h5>\n<ul>\n<li><strong>Shadow IT &amp; AI Discovery:<br \/>\n<\/strong>CloudDR identifiziert s\u00e4mtliche Cloud- und KI-Anwendungen innerhalb der Unternehmensumgebung\u2013 unabh\u00e4ngig davon, ob diese zentral verwaltet werden oder nicht.<\/li>\n<li><strong>Misconfiguration Management:<\/strong><br \/>\nDie L\u00f6sung \u00fcberwacht kontinuierlich Konfigurationen und erkennt riskante Einstellungen oder Konfigurationsabweichungen automatisch. Kritische Probleme k\u00f6nnen dabei direkt behoben werden.<\/li>\n<li><strong>Identity Threat Detection &amp; Response (ITDR):<\/strong><br \/>\nCloudDR erkennt kompromittierte Benutzerkonten und identit\u00e4tsbasierte Angriffe in Echtzeit.<\/li>\n<\/ul>\n<p>Zum Start unterst\u00fctzt die Plattform bereits mehr als 40 Anwendungen, darunter Microsoft 365, OpenAI, Salesforce und Google Workspace. Die L\u00f6sung arbeitet agentenlos und l\u00e4sst sich schnell in bestehende Cloud-Umgebungen integrieren.<\/p>\n<h4>Warum diese Ank\u00fcndigungen relevant sind<\/h4>\n<p>Mit Rai&#x2122; und CloudDR reagiert WatchGuard auf einen grundlegenden Wandel in der Cybersecurity-Landschaft. KI-gest\u00fctzte Angriffe nehmen kontinuierlich zu und werden immer komplexer, w\u00e4hrend gleichzeitig Fachkr\u00e4ftemangel, steigende Sicherheitsanforderungen und die zunehmende Nutzung von Cloud-Diensten Unternehmen vor wachsende Herausforderungen stellen.<\/p>\n<p>Die neuen L\u00f6sungen sollen dabei helfen:<\/p>\n<ul>\n<li data-start=\"4009\" data-end=\"4046\" data-section-id=\"hnvuuo\">Bedrohungen schneller zu erkennen<\/li>\n<li data-start=\"4047\" data-end=\"4098\" data-section-id=\"qdhaq4\">Sicherheitsvorf\u00e4lle automatisiert zu bearbeiten<\/li>\n<li>Reaktionszeiten deutlich zu verk\u00fcrzen<\/li>\n<li data-start=\"4099\" data-end=\"4144\" data-section-id=\"85p58p\">Risiken in Cloud-Umgebungen zu minimieren<\/li>\n<li data-start=\"4145\" data-end=\"4170\" data-section-id=\"c9d63r\">IT-Teams zu entlasten<\/li>\n<\/ul>\n<p>Gerade vor dem Hintergrund wachsender Cyberbedrohungen zeigt sich, wie wichtig moderne, integrierte Sicherheitsl\u00f6sungen f\u00fcr Unternehmen geworden sind.<\/p>\n<p>Weitere Informationen finden Sie bei WatchGuard unter <a href=\"https:\/\/www.watchguard.com\/de\/wgrd-platform\/rai\" target=\"_blank\" rel=\"noopener\">&gt;&gt; Meet Rai<\/a> und <a href=\"https:\/\/www.watchguard.com\/de\/wgrd-products\/sase\/cloud-detection-response\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;&gt; Cloud Detection and Response<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf der diesj\u00e4hrigen Impact Partner Conference in Dubrovnik hat WatchGuard Technologies gleich zwei bedeutende Neuerungen vorgestellt: Rai&#x2122;, eine KI-gest\u00fctzte digitale Workforce, sowie WatchGuard Cloud Detection and Response (CloudDR). Beide L\u00f6sungen adressieren eine zentrale Herausforderung moderner Cybersicherheit: Angriffe werden zunehmend automatisiert, intelligent und rund um die Uhr ausgef\u00fchrt. Klassische Security-Teams sto\u00dfen dabei schnell an ihre Grenzen. Gleichzeitig reduzieren die neuen Technologien operative Aufw\u00e4nde, verk\u00fcrzen Reaktionszeiten und &hellip; <a href=\"https:\/\/wordpress.boc.de\/watchguard-info-portal\/2026\/05\/watchguard-stellt-rai-und-cloud-detection-and-response-vor\/\" class=\"more-link\">Weiterlesen <span class=\"screen-reader-text\">WatchGuard stellt Rai&#x2122; und Cloud Detection and Response vor<\/span> <span class=\"meta-nav\">&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[445],"tags":[964,2708,512,2710,2711,2709,962,963,2707,1360],"class_list":["post-30929","post","type-post","status-publish","format-standard","hentry","category-aktuelle-nachrichten","tag-ai","tag-artificial-intelligence","tag-cloud","tag-cloud-detection-and-response","tag-clouddr","tag-detection-and-response","tag-ki","tag-kuenstliche-intelligenz","tag-rai","tag-watchguard-firebox"],"_links":{"self":[{"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/posts\/30929"}],"collection":[{"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/comments?post=30929"}],"version-history":[{"count":7,"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/posts\/30929\/revisions"}],"predecessor-version":[{"id":30945,"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/posts\/30929\/revisions\/30945"}],"wp:attachment":[{"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/media?parent=30929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/categories?post=30929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wordpress.boc.de\/watchguard-info-portal\/wp-json\/wp\/v2\/tags?post=30929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}